{"id":1998,"date":"2015-06-22T18:03:34","date_gmt":"2015-06-22T16:03:34","guid":{"rendered":"http:\/\/localhost\/blogProclinic\/web\/?p=1998"},"modified":"2015-06-23T11:50:48","modified_gmt":"2015-06-23T09:50:48","slug":"como-diferenciarse-de-otras-clinicas","status":"publish","type":"post","link":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/","title":{"rendered":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?"},"content":{"rendered":"<p><a title=\"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?\" href=\"http:\/\/www.swissdentalmarketing.com\/es\/wp-content\/uploads\/sites\/2\/OdH-Junio-Julio-2015-.pdf\" target=\"_blank\"><span style=\"color: #008080;\"><em>Art\u00edculo publicado por Daniel Izquierdo de Swiss Dental Marketing.<\/em><\/span><\/a><\/p>\n<p><strong>\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica\u00a0dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse\u00a0<\/strong><strong>en medio de la alta competencia?<\/strong> Preguntas importantes\u00a0que no suelen recibir la consideraci\u00f3n adecuada.<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Me gusta provocar a los dentistas que participan en mis\u00a0cursos con la pregunta sobre su posicionamiento. <strong>\u00bfPor\u00a0qu\u00e9 raz\u00f3n debo ir justamente a su cl\u00ednica y no a cualquier\u00a0otra?<\/strong> A menudo se quedan mir\u00e1ndome, perplejos y dudosos,\u00a0ya que la gran mayor\u00eda nunca se ha planteado esta\u00a0cuesti\u00f3n a fondo. Si acaso, <strong>se recurre al argumento de la\u00a0especializaci\u00f3n como criterio para diferenciarse<\/strong>; implantolog\u00eda\u00a0o est\u00e9tica, por ejemplo. Puede que este posicionamiento\u00a0sea suficiente en lugares como Vielha, en el Valle\u00a0de Ar\u00e1n, <strong>pero en grandes ciudades este argumento de diferenciaci\u00f3n\u00a0se queda corto<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Si sigo insistiendo en las <strong>razones por las cuales decidirme\u00a0por una cl\u00ednica dental y otra<\/strong>, suelo recibir argumentos\u00a0como <strong>experiencia, precios atractivos o calidad<\/strong>. Estos\u00a0son, sin duda alguna, aspectos importantes, <strong>sin embargo\u00a0tampoco sirven como criterios de diferenciaci\u00f3n<\/strong> ya que\u00a0muchas cl\u00ednicas suelen decir que tienen experiencia profesional\u00a0o condiciones interesantes.<\/p>\n<blockquote><p>Un posicionamiento\u00a0de verdad se caracteriza por cierto grado de exclusividad\u00a0y distinci\u00f3n. Y el argumento de la calidad tampoco sirve\u00a0como criterio de posicionamiento, ya que es una de esas\u00a0palabras desprovistas de sentido que tanto se usan en publicidad.<\/p><\/blockquote>\n<p>\u201dCalidad\u201d, \u00bfEn qu\u00e9? \u00bfSe refiere acaso a la calidad\u00a0del material o del tratamiento odontol\u00f3gico?. Porque si\u00a0as\u00ed fuese, este argumento no sirve ya que los pacientes no\u00a0son capaces de valorar si una intervenci\u00f3n se ha hecho con\u00a0el mayor cuidado y con la m\u00e1s alta precisi\u00f3n posible.<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #008080;\"><strong>ABRIR LA MENTE,\u00a0CONSEGUIR DIVERSIDAD DE OPINIONES<\/strong><\/span><\/p>\n<p>Si bien el tratamiento odontol\u00f3gico es la prestaci\u00f3n m\u00e1s\u00a0esencial de una cl\u00ednica dental, puede que no sea la m\u00e1s importante\u00a0y, sin duda alguna, no es la \u00fanica. <strong>El trato al paciente,\u00a0la motivaci\u00f3n de \u00e9ste o el asesoramiento en cuestiones\u00a0de la salud buco-dental son algunos de los aspectos\u00a0que forman el conjunto de prestaciones que debe ofrecer\u00a0una cl\u00ednica dental.<\/strong> Por lo tanto es recomendable a\u00f1adir\u00a0a los aspectos odontol\u00f3gicos, argumentos de posicionamiento,\u00a0como las propiedades del equipo profesional o las\u00a0prestaciones adicionales.<\/p>\n<p>\u00bfExisten aspectos que destacan al personal de la cl\u00ednica?\u00a0\u00bfHablan todos perfectamente ingl\u00e9s o ruso? \u00bfO han sido\u00a0todos formados en la atenci\u00f3n de pacientes con temor al\u00a0dentista? \u00bfAcaso trabajan \u00fanicamente profesionales con\u00a0m\u00e1s de diez a\u00f1os de experiencia? Argumentos interesantes\u00a0puede haber tantos como personal en plantilla.<\/p>\n<p>Aunque sean detalles,<strong> las prestaciones adicionales pueden\u00a0reforzar la distinci\u00f3n de una cl\u00ednica<\/strong>. En general son\u00a0aspectos relacionados con la percepci\u00f3n del paciente antes,\u00a0durante y despu\u00e9s de la visita. \u00bfExisten, por ejemplo,\u00a0aparcamientos reservados para los pacientes? \u00bfSe ofrecen\u00a0horarios especiales? \u00bfAcaso Santiago Calatrava ha dise\u00f1ado el interiorismo de la cl\u00ednica? \u00bfO hemos colaborado\u00a0con la ONCE y creado una cl\u00ednica especialmente adaptada\u00a0para invidentes?<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #008080;\"><strong>EXISTEN BUENAS RAZONES PARA REFLEXIONAR\u00a0SOBRE EL POSICIONAMIENTO<\/strong><\/span><\/p>\n<p><strong>Hay muchas razones por las cuales vale la pena invertir\u00a0tiempo y empe\u00f1o en definir el posicionamiento de una cl\u00ednica dental.<\/strong> A continuaci\u00f3n una breve selecci\u00f3n:<\/p>\n<p><strong>1\u00aa raz\u00f3n:<\/strong> Verificar el estatus quo. <strong>\u00bfSomos realmente percibidos\u00a0tal y como lo deseamos?<\/strong> \u00bfO ha cambiado algo en\u00a0los \u00faltimos a\u00f1os?<br \/>\n<strong>2\u00aa raz\u00f3n:<\/strong> <strong>Un posicionamiento bien claro fomenta el nivel\u00a0de reconocimiento<\/strong>, que es igual de importante para la fidelizaci\u00f3n de los pacientes existentes como para conseguir\u00a0nuevas visitas.<br \/>\n<strong>3\u00aa raz\u00f3n:<\/strong> Cuanto <strong>m\u00e1s alto sea el nivel de reconocimiento\u00a0m\u00e1s probable es que un paciente<\/strong> se acuerde de su dentista\u00a0y <strong>lo recomiende<\/strong> cuando se le pida una recomendaci\u00f3n.<br \/>\n<strong>4\u00aa raz\u00f3n:<\/strong> Cuanto <strong>m\u00e1s claro sea el posicionamiento m\u00e1s\u00a0dif\u00edcil ser\u00e1 que otras cl\u00ednicas copien el modelo<\/strong> o la idea.<\/p>\n<p><strong>5\u00aa raz\u00f3n:<\/strong> <strong>S\u00f3lo con un posicionamiento realmente expl\u00edcito se atraer\u00e1 a los pacientes con el perfil deseado<\/strong>. Y ya\u00a0que \u00e9stos eligen a su dentista justamente por su posicionamiento,\u00a0m\u00e1s f\u00e1cil ser\u00e1 ganarlos como punto de partida del\u00a0boca-a-boca.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Art\u00edculo publicado por Daniel Izquierdo de Swiss Dental Marketing. \u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica\u00a0dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse\u00a0en medio de la alta competencia? Preguntas importantes\u00a0que no suelen recibir la consideraci\u00f3n adecuada.<\/p>\n","protected":false},"author":101011,"featured_media":2008,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic<\/title>\n<meta name=\"description\" content=\"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic\" \/>\n<meta property=\"og:description\" content=\"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Proclinic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proclinicsa\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-22T16:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-23T09:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"956\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Proclinic_SA\" \/>\n<meta name=\"twitter:site\" content=\"@Proclinic_SA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/\"},\"author\":{\"name\":\"Anna\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/85e304ea367ce3922003b0d8b388e527\"},\"headline\":\"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?\",\"datePublished\":\"2015-06-22T16:03:34+00:00\",\"dateModified\":\"2015-06-23T09:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/\"},\"wordCount\":732,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/posicionamiento.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/\",\"name\":\"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/posicionamiento.jpg\",\"datePublished\":\"2015-06-22T16:03:34+00:00\",\"dateModified\":\"2015-06-23T09:50:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/85e304ea367ce3922003b0d8b388e527\"},\"description\":\"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/posicionamiento.jpg\",\"contentUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/posicionamiento.jpg\",\"width\":956,\"height\":607,\"caption\":\"Diferenciaci\u00f3n cl\u00ednicas dentales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/como-diferenciarse-de-otras-clinicas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/\",\"name\":\"Blog Proclinic\",\"description\":\"\u00a1Bienvenido al blog de Proclinic! En este espacio, nos enfocamos en brindar informaci\u00f3n valiosa y actualizada para todos los profesionales del sector dental. Nuestra misi\u00f3n es mantenerte al d\u00eda de las \u00faltimas tendencias, investigaciones y t\u00e9cnicas en el campo de la odontolog\u00eda. Exploraremos temas que van desde las novedades en materiales odontol\u00f3gicos, consejos pr\u00e1cticos para la gesti\u00f3n de cl\u00ednicas dentales hasta casos cl\u00ednicos con base cient\u00edfica, eventos del sector y mucho m\u00e1s. Te invitamos a seguir nuestro contenido, dise\u00f1ado para mantener tu pr\u00e1ctica en la vanguardia de la odontolog\u00eda moderna.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/85e304ea367ce3922003b0d8b388e527\",\"name\":\"Anna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g\",\"caption\":\"Anna\"},\"description\":\"Community Manager\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/author\\\/anna\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic","description":"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic","og_description":"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?","og_url":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/","og_site_name":"Blog Proclinic","article_publisher":"https:\/\/www.facebook.com\/proclinicsa","article_published_time":"2015-06-22T16:03:34+00:00","article_modified_time":"2015-06-23T09:50:48+00:00","og_image":[{"width":956,"height":607,"url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","type":"image\/jpeg"}],"author":"Anna","twitter_card":"summary_large_image","twitter_creator":"@Proclinic_SA","twitter_site":"@Proclinic_SA","twitter_misc":{"Escrito por":"Anna","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#article","isPartOf":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/"},"author":{"name":"Anna","@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/85e304ea367ce3922003b0d8b388e527"},"headline":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?","datePublished":"2015-06-22T16:03:34+00:00","dateModified":"2015-06-23T09:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/"},"wordCount":732,"commentCount":0,"image":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","articleSection":["Actualidad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/","url":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/","name":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas? - Blog Proclinic","isPartOf":{"@id":"https:\/\/www.proclinic.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#primaryimage"},"image":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","datePublished":"2015-06-22T16:03:34+00:00","dateModified":"2015-06-23T09:50:48+00:00","author":{"@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/85e304ea367ce3922003b0d8b388e527"},"description":"\u00bfCu\u00e1les son los aspectos que diferencian una cl\u00ednica dental de otra? \u00bfQu\u00e9 criterios existen para posicionarse en medio de la alta competencia?","breadcrumb":{"@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#primaryimage","url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","contentUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","width":956,"height":607,"caption":"Diferenciaci\u00f3n cl\u00ednicas dentales"},{"@type":"BreadcrumbList","@id":"https:\/\/www.proclinic.es\/blog\/como-diferenciarse-de-otras-clinicas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.proclinic.es\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo diferenciarse de otras cl\u00ednicas?"}]},{"@type":"WebSite","@id":"https:\/\/www.proclinic.es\/blog\/#website","url":"https:\/\/www.proclinic.es\/blog\/","name":"Blog Proclinic","description":"\u00a1Bienvenido al blog de Proclinic! En este espacio, nos enfocamos en brindar informaci\u00f3n valiosa y actualizada para todos los profesionales del sector dental. Nuestra misi\u00f3n es mantenerte al d\u00eda de las \u00faltimas tendencias, investigaciones y t\u00e9cnicas en el campo de la odontolog\u00eda. Exploraremos temas que van desde las novedades en materiales odontol\u00f3gicos, consejos pr\u00e1cticos para la gesti\u00f3n de cl\u00ednicas dentales hasta casos cl\u00ednicos con base cient\u00edfica, eventos del sector y mucho m\u00e1s. Te invitamos a seguir nuestro contenido, dise\u00f1ado para mantener tu pr\u00e1ctica en la vanguardia de la odontolog\u00eda moderna.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proclinic.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/85e304ea367ce3922003b0d8b388e527","name":"Anna","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8b19455b6924f97d0afcdeb2791066e8c8af798468c71e0fe7e686c5d0b49f4?s=96&d=mm&r=g","caption":"Anna"},"description":"Community Manager","url":"https:\/\/www.proclinic.es\/blog\/author\/anna\/"}]}},"jetpack_featured_media_url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2015\/06\/posicionamiento.jpg","_links":{"self":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/1998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/users\/101011"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/comments?post=1998"}],"version-history":[{"count":9,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/1998\/revisions"}],"predecessor-version":[{"id":2009,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/1998\/revisions\/2009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/media\/2008"}],"wp:attachment":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/media?parent=1998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/categories?post=1998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/tags?post=1998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}