{"id":14574,"date":"2024-06-25T09:00:00","date_gmt":"2024-06-25T07:00:00","guid":{"rendered":"https:\/\/www.proclinic.es\/blog\/?p=14574"},"modified":"2024-06-21T14:51:54","modified_gmt":"2024-06-21T12:51:54","slug":"rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion","status":"publish","type":"post","link":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/","title":{"rendered":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n"},"content":{"rendered":"<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px-800x423.webp\" alt=\"\" class=\"wp-image-14575\" style=\"width:804px;height:425px\" width=\"804\" height=\"425\" srcset=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px-800x423.webp 800w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px-300x159.webp 300w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px-768x406.webp 768w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp 1200w\" sizes=\"auto, (max-width: 804px) 100vw, 804px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Kuraray Noritake Dental es pionero en el campo de los adhesivos dentales gracias al desarrollo del mon\u00f3mero original 10-MDP. Patentado en 1981, el mon\u00f3mero fue utilizado dos a\u00f1os despu\u00e9s en el cemento compuesto PANAVIA\u2122 EX y desde entonces ha constituido el pilar fundamental de muchos otros productos exitosos. Ahora la empresa ha combinado el mon\u00f3mero MDP original con mon\u00f3meros de amida hidr\u00f3filos para desarrollar la tecnolog\u00eda de adhesi\u00f3n r\u00e1pida (Rapid Bond Technology), que es la base de <a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL\u2122 Universal Bond Quick,<\/a> la soluci\u00f3n adhesiva universal emblem\u00e1tica de la historia de \u00e9xito y del compromiso con la innovaci\u00f3n de Kuraray Noritake Dental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los avances de la tecnolog\u00eda moderna de adhesi\u00f3n dental han llevado a una reducci\u00f3n de la cantidad de componentes necesarios para los procesos de mordiente total y self-etch. No obstante, la gesti\u00f3n b\u00e1sica de estos adhesivos no se ha modificado mucho. Muchos adhesivos requieren agitar el frasco antes de su uso, frotar el l\u00edquido por mucho tiempo y\/o esperar durante un determinado per\u00edodo de tiempo. A menudo es necesario aplicar varias capas. La dependencia de mon\u00f3meros de penetraci\u00f3n lenta significa que, para los adhesivos tradicionales en frasco, la adhesi\u00f3n a la dif\u00edcil capa de dentina es un proceso lento y sensible a la t\u00e9cnica.<\/p>\n\n\n<div class=\"wp-block-image is-style-default\">\n<figure class=\"aligncenter size-large\"><a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"467\" src=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Inbetween_banner_929x542-800x467.webp\" alt=\"\" class=\"wp-image-14577\" srcset=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Inbetween_banner_929x542-800x467.webp 800w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Inbetween_banner_929x542-300x175.webp 300w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Inbetween_banner_929x542-768x448.webp 768w, https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Inbetween_banner_929x542.webp 929w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Gracias a la integraci\u00f3n de mon\u00f3meros de amida de nueva concepci\u00f3n, la Rapid Bond Technology otorga a <a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL Universal Bond Quick <\/a>excelentes propiedades hidr\u00f3filas y la capacidad de penetrar en modo r\u00e1pido y eficaz en la dentina h\u00fameda. No es necesario esperar a que se seque con el aire despu\u00e9s de la aplicaci\u00f3n antes de continuar &#8211; dicho tiempo se ha eliminado &#8211; y tras la fotopolimerizaci\u00f3n se crea un sellado fuerte y duradero de la cavidad. El procedimiento de adhesi\u00f3n con <a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL Universal Bond Quick <\/a>es sencillo y eficaz y garantiza resultados cl\u00ednicos predecibles, gracias a la tecnolog\u00eda de adhesi\u00f3n r\u00e1pida.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_86 counter-hierarchy ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0098a7;color:#0098a7\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #0098a7;color:#0098a7\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#Absorcion_de_agua_increiblemente_baja\" >Absorci\u00f3n de agua&nbsp;incre\u00edblemente baja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#Adhesion_estetica_y_eficaz\" >Adhesi\u00f3n est\u00e9tica y eficaz<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Absorcion_de_agua_increiblemente_baja\"><\/span><strong>Absorci\u00f3n de agua&nbsp;incre\u00edblemente baja<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los indicadores m\u00e1s importantes del \u00e9xito a largo plazo de la adhesi\u00f3n a la dentina es el nivel de absorci\u00f3n del agua de la matriz org\u00e1nica del adhesivo. Una alta tasa de absorci\u00f3n del agua ha sido relacionada cl\u00ednicamente con el continuo deterioro f\u00edsico de las uniones, lo que puede llevar al desarrollo de caries secundarias. Por ese motivo, hemos escogido mantener el contenido de HEMA lo m\u00e1s bajo posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL Universal Bond Quick<\/a> crea una red polim\u00e9rica altamente reticulada gracias a los mon\u00f3meros de amida utilizados en la Rapid Bond Technology. En consecuencia, la tasa de absorci\u00f3n de agua es relativamente baja, lo cual significa que estos pol\u00edmeros reticulados son m\u00e1s estables a largo plazo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Adhesion_estetica_y_eficaz\"><\/span><strong>Adhesi\u00f3n est\u00e9tica y eficaz<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La tecnolog\u00eda de adhesi\u00f3n r\u00e1pida no provee solo una base para la excelencia de la adhesi\u00f3n de larga duraci\u00f3n. La fina capa (5-10 \u03bcm) de <a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL Universal Bond Quick<\/a> brinda a las restauraciones una excelente est\u00e9tica y su red polim\u00e9rica densamente reticulada refuerza la estabilidad de esta capa externa y proporciona resistencia a la decoloraci\u00f3n marginal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al combinar el mon\u00f3mero MDP original de Kuraray Noritake Dental con mon\u00f3meros de amida hidr\u00f3filos, la Rapid Bond Technology es el motor que alimenta <a href=\"\/\/www.proclinic.es\/tienda\/products\/search?references=90058,24672,24711\">CLEARFIL Universal Bond Quick<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kuraray Noritake Dental es pionero en el campo de los adhesivos dentales gracias al desarrollo del mon\u00f3mero original 10-MDP. Patentado en 1981, el mon\u00f3mero fue utilizado dos a\u00f1os despu\u00e9s en el cemento compuesto PANAVIA\u2122 EX y desde entonces ha constituido el pilar fundamental de muchos otros productos exitosos. Ahora la empresa ha combinado el mon\u00f3mero &#8230; <a title=\"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n\" class=\"read-more\" href=\"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/\" aria-label=\"More on Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n\">Read more<\/a><\/p>\n","protected":false},"author":101016,"featured_media":14575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[310,63],"class_list":["post-14574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-clinica-dental","tag-adhesivo-universal","tag-proclinic"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic\" \/>\n<meta property=\"og:description\" content=\"Kuraray Noritake Dental es pionero en el campo de los adhesivos dentales gracias al desarrollo del mon\u00f3mero original 10-MDP. Patentado en 1981, el mon\u00f3mero fue utilizado dos a\u00f1os despu\u00e9s en el cemento compuesto PANAVIA\u2122 EX y desde entonces ha constituido el pilar fundamental de muchos otros productos exitosos. Ahora la empresa ha combinado el mon\u00f3mero ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Proclinic\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proclinicsa\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-25T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Paula Ruiz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Proclinic_SA\" \/>\n<meta name=\"twitter:site\" content=\"@Proclinic_SA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Ruiz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/\"},\"author\":{\"name\":\"Paula Ruiz\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/aeb6b71a104c6452f2b19e8838b3d5d1\"},\"headline\":\"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n\",\"datePublished\":\"2024-06-25T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/\"},\"wordCount\":598,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/22424_1_Header_1200x635px.webp\",\"keywords\":[\"adhesivo universal\",\"proclinic\"],\"articleSection\":[\"Cl\u00ednica Dental\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/\",\"name\":\"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/22424_1_Header_1200x635px.webp\",\"datePublished\":\"2024-06-25T07:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/aeb6b71a104c6452f2b19e8838b3d5d1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/22424_1_Header_1200x635px.webp\",\"contentUrl\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/22424_1_Header_1200x635px.webp\",\"width\":1200,\"height\":635},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/\",\"name\":\"Blog Proclinic\",\"description\":\"\u00a1Bienvenido al blog de Proclinic! En este espacio, nos enfocamos en brindar informaci\u00f3n valiosa y actualizada para todos los profesionales del sector dental. Nuestra misi\u00f3n es mantenerte al d\u00eda de las \u00faltimas tendencias, investigaciones y t\u00e9cnicas en el campo de la odontolog\u00eda. Exploraremos temas que van desde las novedades en materiales odontol\u00f3gicos, consejos pr\u00e1cticos para la gesti\u00f3n de cl\u00ednicas dentales hasta casos cl\u00ednicos con base cient\u00edfica, eventos del sector y mucho m\u00e1s. Te invitamos a seguir nuestro contenido, dise\u00f1ado para mantener tu pr\u00e1ctica en la vanguardia de la odontolog\u00eda moderna.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/#\\\/schema\\\/person\\\/aeb6b71a104c6452f2b19e8838b3d5d1\",\"name\":\"Paula Ruiz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g\",\"caption\":\"Paula Ruiz\"},\"url\":\"https:\\\/\\\/www.proclinic.es\\\/blog\\\/author\\\/paula-ruizproclinic-es\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/","og_locale":"es_ES","og_type":"article","og_title":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic","og_description":"Kuraray Noritake Dental es pionero en el campo de los adhesivos dentales gracias al desarrollo del mon\u00f3mero original 10-MDP. Patentado en 1981, el mon\u00f3mero fue utilizado dos a\u00f1os despu\u00e9s en el cemento compuesto PANAVIA\u2122 EX y desde entonces ha constituido el pilar fundamental de muchos otros productos exitosos. Ahora la empresa ha combinado el mon\u00f3mero ... Read more","og_url":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/","og_site_name":"Blog Proclinic","article_publisher":"https:\/\/www.facebook.com\/proclinicsa","article_published_time":"2024-06-25T07:00:00+00:00","og_image":[{"width":1200,"height":635,"url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","type":"image\/webp"}],"author":"Paula Ruiz","twitter_card":"summary_large_image","twitter_creator":"@Proclinic_SA","twitter_site":"@Proclinic_SA","twitter_misc":{"Escrito por":"Paula Ruiz","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#article","isPartOf":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/"},"author":{"name":"Paula Ruiz","@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/aeb6b71a104c6452f2b19e8838b3d5d1"},"headline":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n","datePublished":"2024-06-25T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/"},"wordCount":598,"commentCount":0,"image":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","keywords":["adhesivo universal","proclinic"],"articleSection":["Cl\u00ednica Dental"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/","url":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/","name":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n - Blog Proclinic","isPartOf":{"@id":"https:\/\/www.proclinic.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#primaryimage"},"image":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","datePublished":"2024-06-25T07:00:00+00:00","author":{"@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/aeb6b71a104c6452f2b19e8838b3d5d1"},"breadcrumb":{"@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#primaryimage","url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","contentUrl":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","width":1200,"height":635},{"@type":"BreadcrumbList","@id":"https:\/\/www.proclinic.es\/blog\/rapid-bond-technology-adhesion-instantanea-y-de-larga-duracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.proclinic.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Rapid Bond Technology: adhesi\u00f3n instant\u00e1nea y de larga duraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.proclinic.es\/blog\/#website","url":"https:\/\/www.proclinic.es\/blog\/","name":"Blog Proclinic","description":"\u00a1Bienvenido al blog de Proclinic! En este espacio, nos enfocamos en brindar informaci\u00f3n valiosa y actualizada para todos los profesionales del sector dental. Nuestra misi\u00f3n es mantenerte al d\u00eda de las \u00faltimas tendencias, investigaciones y t\u00e9cnicas en el campo de la odontolog\u00eda. Exploraremos temas que van desde las novedades en materiales odontol\u00f3gicos, consejos pr\u00e1cticos para la gesti\u00f3n de cl\u00ednicas dentales hasta casos cl\u00ednicos con base cient\u00edfica, eventos del sector y mucho m\u00e1s. Te invitamos a seguir nuestro contenido, dise\u00f1ado para mantener tu pr\u00e1ctica en la vanguardia de la odontolog\u00eda moderna.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proclinic.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.proclinic.es\/blog\/#\/schema\/person\/aeb6b71a104c6452f2b19e8838b3d5d1","name":"Paula Ruiz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/75d7314ad27214b55512e1927624b8e519450adb231f20432cee5b7a678f9e35?s=96&d=mm&r=g","caption":"Paula Ruiz"},"url":"https:\/\/www.proclinic.es\/blog\/author\/paula-ruizproclinic-es\/"}]}},"jetpack_featured_media_url":"https:\/\/www.proclinic.es\/blog\/wp-content\/uploads\/2024\/06\/22424_1_Header_1200x635px.webp","_links":{"self":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/14574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/users\/101016"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/comments?post=14574"}],"version-history":[{"count":5,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/14574\/revisions"}],"predecessor-version":[{"id":14583,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/posts\/14574\/revisions\/14583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/media\/14575"}],"wp:attachment":[{"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/media?parent=14574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/categories?post=14574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.proclinic.es\/blog\/wp-json\/wp\/v2\/tags?post=14574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}